{"id":4995,"date":"2020-08-04T10:22:00","date_gmt":"2020-08-04T13:22:00","guid":{"rendered":"https:\/\/www.casamagalhaes.com.br\/blog\/?p=4995"},"modified":"2020-08-06T17:07:03","modified_gmt":"2020-08-06T20:07:03","slug":"treinamento-de-atendimento-ao-cliente","status":"publish","type":"post","link":"https:\/\/www.casamagalhaes.com.br\/blog\/gestao-de-empresas\/treinamento-de-atendimento-ao-cliente\/","title":{"rendered":"4 motivos para investir no treinamento de atendimento ao cliente!"},"content":{"rendered":"<p>Conquistar novos consumidores diante de tanta concorr\u00eancia \u00e9 uma miss\u00e3o para poucos, e mant\u00ea-los fiel ao seu neg\u00f3cio \u00e9 s\u00f3 para quem investe em treinamento de atendimento ao cliente.&nbsp;<\/p>\n<p>As empresas que ainda n\u00e3o se deram conta da import\u00e2ncia da capacita\u00e7\u00e3o desse time est\u00e3o fadadas ao fracasso. Simples assim!<\/p>\n<p>As afirma\u00e7\u00f5es que voc\u00ea acabou de ler parecem extrapolar o dramatismo, mas s\u00e3o reais. A equipe de atendimento \u00e9 respons\u00e1vel pelo contato que a sua empresa mant\u00e9m com os clientes. Por isso, o que voc\u00ea est\u00e1 fazendo ao investir no treinamento de atendimento ao cliente \u00e9, na verdade, uma aposta na otimiza\u00e7\u00e3o de resultados e no <a href=\"https:\/\/www.casamagalhaes.com.br\/blog\/supermercado-e-varejo\/estrategias-aumentar-as-vendas\/\">aumento das vendas<\/a>.<\/p>\n<p>O custo-benef\u00edcio do treinamento para melhor capacita\u00e7\u00e3o da equipe de atendimento pode ser equiparado ao custo de aquisi\u00e7\u00e3o de cliente (CAC). Portanto, cada consumidor perdido por n\u00e3o ter sido atendido de forma adequada significa o desperd\u00edcio da verba aplicada na conquista dele.<\/p>\n<p>Elaboramos este post para mostrar alguns motivos para investir em treinamento de atendimento ao cliente e de que modo capacitar seus colaboradores nesse aspecto. Confira!<\/p>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_83 counter-hierarchy ez-toc-counter ez-toc-light-blue ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Navegue pelo conte\u00fado<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Alternar tabela de conte\u00fado\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/www.casamagalhaes.com.br\/blog\/gestao-de-empresas\/treinamento-de-atendimento-ao-cliente\/#Conheca_os_principais_meios_de_treinamento_de_atendimento_ao_cliente\" >Conhe\u00e7a os principais meios de treinamento de atendimento ao cliente<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/www.casamagalhaes.com.br\/blog\/gestao-de-empresas\/treinamento-de-atendimento-ao-cliente\/#Conheca_4_motivos_para_investir_no_treinamento_da_equipe_de_atendimento\" >Conhe\u00e7a 4 motivos para investir no treinamento da equipe de atendimento<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/www.casamagalhaes.com.br\/blog\/gestao-de-empresas\/treinamento-de-atendimento-ao-cliente\/#Saiba_quais_sao_as_melhores_formas_de_treinamento_de_atendimento_ao_cliente\" >Saiba quais s\u00e3o as melhores formas de treinamento de atendimento ao cliente<\/a><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"Conheca_os_principais_meios_de_treinamento_de_atendimento_ao_cliente\"><\/span><b>Conhe\u00e7a os principais meios de treinamento de atendimento ao cliente<\/b><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Existem diversos modos de capacitar a sua equipe de atendimento para que ela ofere\u00e7a um excelente servi\u00e7o aos clientes, garantindo a <a href=\"https:\/\/www.casamagalhaes.com.br\/blog\/marketing\/como-fidelizar-clientes\/\">fideliza\u00e7\u00e3o<\/a> deles \u00e0 empresa e o fechamento de novos neg\u00f3cios. Nos t\u00f3picos a seguir voc\u00ea vai conhecer os principais deles. Veja!<\/p>\n<h3><b>Treinamento de atendimento ao cliente Presencial<\/b><\/h3>\n<p>O m\u00e9todo de treinamento de atendimento ao cliente presencial \u00e9 o mais comum e conhecido de todos. Por meio dele, palestrantes e instrutores s\u00e3o contratados pela empresa para levar novos conhecimentos \u00e0 equipe de atendimento, em eventos que poder\u00e3o acontecer dentro da empresa ou em institui\u00e7\u00f5es de ensino especializadas no assunto.<\/p>\n<h3><b>Educa\u00e7\u00e3o \u00e0 dist\u00e2ncia<\/b><\/h3>\n<p>A educa\u00e7\u00e3o \u00e0 dist\u00e2ncia vem ganhando cada vez mais espa\u00e7o, principalmente para o aprendizado de nicho. Afinal, todos os dias novos <a href=\"https:\/\/www.casamagalhaes.com.br\/blog\/marketing\/como-fidelizar-clientes\/\">cursos <\/a>especializados surgem espalhados pela web, do mesmo que modo que as plataformas de desenvolvimento pessoal \u2014 personalizadas para as necessidades de uma empresa \u2014 tamb\u00e9m est\u00e3o se tornando cada vez mais comuns.<\/p>\n<p>Muitos colaboradores utilizam, por exemplo, o tempo que est\u00e3o a caminho do trabalho para estudar em seus dispositivos m\u00f3veis. Desse modo, se a empresa oferecer algum treinamento de atendimento ao cliente por meios digitais, ele certamente poder\u00e1 ser feito nesse per\u00edodo \u201cocioso\u201d.<\/p>\n<h3><b>Troca de conhecimento entre a equipe<\/b><\/h3>\n<p>Outro meio eficiente de treinamento de atendimento ao cliente \u00e9 a troca de experi\u00eancias entre os membros de uma mesma <a href=\"https:\/\/www.casamagalhaes.com.br\/blog\/vendas\/motivar-equipe-de-vendas\/\">equipe<\/a>. O conhecimento emp\u00edrico \u00e9 o mais raro, caro e confi\u00e1vel de todos. Logo, ele \u00e9 aquele adquirido por meio da \u201cm\u00e3o na massa\u201d, e muitas vezes mais valoroso do que o cient\u00edfico.<\/p>\n<p>Por isso, investir algum tempo para que os colaboradores da equipe de atendimento troquem informa\u00e7\u00f5es entre si por meio de palestras e semin\u00e1rios preparados por eles pr\u00f3prios \u00e9 uma \u00f3tima maneira de treinar os colaboradores com baix\u00edssimo<a href=\"https:\/\/www.casamagalhaes.com.br\/blog\/financas\/gestao-de-custos\/\"> custo.<\/a><\/p>\n<p>Experimente estabelecer um hor\u00e1rio semanal fixo para que o evento de troca de conhecimento aconte\u00e7a, fazendo com que a cada semana um colaborador seja o respons\u00e1vel pela prepara\u00e7\u00e3o da palestra. Dessa forma, voc\u00ea vai ver quantos conhecimentos interessantes e valiosos surgir\u00e3o da pr\u00e1tica.<\/p>\n<p>Os seus colaboradores poder\u00e3o simplesmente contar a hist\u00f3ria de atendimentos bem-sucedidos durante as sess\u00f5es internas de treinamento de vendas, deixando a experi\u00eancia como ensinamento para os demais integrantes da equipe \u2014 e at\u00e9 mesmo para os colaboradores das outras \u00e1reas da empresa.<\/p>\n<h3><b>Programas de incentivo \u00e0 educa\u00e7\u00e3o<\/b><\/h3>\n<p>Se voc\u00ea j\u00e1 ouviu falar em Recursos Humanos 4.0, sabe do que estamos falando. Hoje em dia, muitas empresas utilizam bolsas de estudo \u2014 mesmo que parciais \u2014 como modo de premiar bons colaboradores.&nbsp;<\/p>\n<p>Por que n\u00e3o adotar essa pr\u00e1tica para premiar os profissionais que se destacam na \u00e1rea de atendimento ao cliente?<\/p>\n<p>Al\u00e9m deles se qualificarem com o incentivo \u00e0 educa\u00e7\u00e3o oferecido pela empresa como pr\u00eamio, esses profissionais ainda podem compartilhar o conhecimento adquirido com os demais membros da equipe. J\u00e1 pensou nisso?<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Conheca_4_motivos_para_investir_no_treinamento_da_equipe_de_atendimento\"><\/span><b>Conhe\u00e7a 4 motivos para investir no treinamento da equipe de atendimento<\/b><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Qualquer \u00e1rea de uma empresa \u00e9 beneficiada com a qualifica\u00e7\u00e3o de seus colaboradores, e isso n\u00e3o seria diferente com a equipe de atendimento. No entanto, a capacita\u00e7\u00e3o desse time beneficia toda a empresa, uma vez que estimula a aquisi\u00e7\u00e3o e a manuten\u00e7\u00e3o de clientes \u2014 que s\u00e3o os reais geradores de receitas de uma organiza\u00e7\u00e3o.<\/p>\n<p>Se pensarmos al\u00e9m do modo hol\u00edstico, ainda existem benef\u00edcios mais espec\u00edficos para o investimento em treinamento de atendimento ao cliente. Confira alguns deles a seguir:<\/p>\n<h3><b>1. Alinhamento com os prop\u00f3sitos e valores da empresa<\/b><\/h3>\n<p>Muitas vezes uma palavra errada dita pelo atendimento de uma empresa pode compromet\u00ea-la \u2014 at\u00e9 mesmo juridicamente \u2014, tirando dela a raz\u00e3o, ainda que esteja agindo de modo correto.<\/p>\n<p>Para evitar que a sua empresa seja obrigada a provar que \u201cnariz de porco n\u00e3o \u00e9 tomada\u201d, \u00e9 fundamental que a sua equipe esteja muito bem alinhada com os prop\u00f3sitos, os valores e as regras do neg\u00f3cio. Desse modo, os funcion\u00e1rios n\u00e3o transmitem ao cliente qualquer ideia ou impress\u00e3o diferente daquelas praticadas pela empresa.<\/p>\n<h3><b>2. Satisfa\u00e7\u00e3o dos clientes<\/b><\/h3>\n<p>Uma equipe bem treinada sabe que \u201cnem sempre o cliente tem raz\u00e3o\u201d. Por\u00e9m, mesmo quando ele estiver errado, precisa ser bem atendido e ter o seu problema solucionado. Nesse contexto, a empatia e a proatividade s\u00e3o fundamentais para que o cliente se sinta <a href=\"https:\/\/www.casamagalhaes.com.br\/blog\/ponto-de-venda\/aumentar-satisfacao-do-cliente\/\">satisfeito<\/a>.<\/p>\n<p>Essas duas caracter\u00edsticas podem ser adquiridas e treinadas pela sua equipe. Portanto, n\u00e3o deixe de treinar os seus colaboradores para manterem seus clientes sempre satisfeitos.<\/p>\n<h3><b>3. Fideliza\u00e7\u00e3o dos clientes<\/b><\/h3>\n<p>Por mais \u00f3bvio que pare\u00e7a, isto precisa ser dito: clientes satisfeitos s\u00e3o fi\u00e9is. Portanto, investir no treinamento de atendimento ao cliente \u00e9 uma forma de fideliz\u00e1-lo. Quando isso acontece, a sua base de clientes ativos s\u00f3 aumenta, o que leva a sua empresa ao crescimento.<\/p>\n<h3><b>4. Motiva\u00e7\u00e3o da equipe<\/b><\/h3>\n<p>Claro que uma equipe que recebe treinamento se sente mais valorizada, uma vez que percebe a preocupa\u00e7\u00e3o da empresa com a sua qualifica\u00e7\u00e3o, al\u00e9m de enxergar oportunidades de crescimento profissional e pessoal. Portanto, um time treinado \u00e9 um time motivado!<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Saiba_quais_sao_as_melhores_formas_de_treinamento_de_atendimento_ao_cliente\"><\/span><b>Saiba quais s\u00e3o as melhores formas de treinamento de atendimento ao cliente<\/b><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Embora algumas das dicas aqui apresentadas pare\u00e7am f\u00e1ceis de serem seguidas \u2014 como os treinamentos a dist\u00e2ncia e as trocas de conhecimento entre membros da equipe \u2014, a ajuda de profissionais especializados \u00e9 sempre muito bem-vinda para que o aproveitamento desses recursos seja otimizado e os resultados alcan\u00e7ados sejam mais significativos.<\/p>\n<p>Por isso, \u00e9 muito importante contar com a ajuda de empresas especializadas em treinar pessoas para uma abordagem de vendas mais precisa e coerente com o produto ou servi\u00e7o que est\u00e1 sendo comercializado.<\/p>\n<p>Para entender melhor como uma empresa de treinamento de atendimento ao cliente pode ajudar voc\u00ea,<a href=\"https:\/\/www.goakira.com.br\/\"> entre em contato com a nossa parceira Goakira<\/a> e saiba como capacitar a sua equipe!<\/p>\n<p>E n\u00e3o esque\u00e7a de assinar nossa Newsletter para receber os melhores conte\u00fados para turbinar as vendas na sua empresa!<\/p>\n<div role=\"main\" id=\"cta-rodape-post-blog-cadastro-newsletter-5225678ea3f96bcfaa68\"><\/div>\n<p><script type=\"text\/javascript\" src=\"https:\/\/d335luupugsy2.cloudfront.net\/js\/rdstation-forms\/stable\/rdstation-forms.min.js\"><\/script><br \/>\n<script type=\"text\/javascript\">\n  new RDStationForms('cta-rodape-post-blog-cadastro-newsletter-5225678ea3f96bcfaa68-html', 'UA-45095125-1').createForm();\n<\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Voc\u00ea investe no treinamento de atendimento ao cliente da sua empresa? Confira os 4 motivos para investir nesse treinamento e a melhor forma de faz\u00ea-lo!<\/p>\n","protected":false},"author":3,"featured_media":4999,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"episode_type":"","audio_file":"","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","itunes_episode_number":"","itunes_title":"","itunes_season_number":"","itunes_episode_type":"","ngg_post_thumbnail":0,"footnotes":""},"categories":[148,154],"tags":[108,113],"class_list":["post-4995","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-atendimento","category-gestao-de-empresas","tag-atendimento","tag-gestao"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>4 motivos para investir no treinamento de atendimento ao cliente!<\/title>\n<meta name=\"description\" content=\"Voc\u00ea investe notreinamento de atendimento ao cliente da sua empresa? Confira os 4 motivos para investir nesse treinamento e a melhor forma de faz\u00ea-lo!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.casamagalhaes.com.br\/blog\/gestao-de-empresas\/treinamento-de-atendimento-ao-cliente\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"4 motivos para investir no treinamento de atendimento ao cliente!\" \/>\n<meta property=\"og:description\" content=\"Voc\u00ea investe notreinamento de atendimento ao cliente da sua empresa? Confira os 4 motivos para investir nesse treinamento e a melhor forma de faz\u00ea-lo!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.casamagalhaes.com.br\/blog\/gestao-de-empresas\/treinamento-de-atendimento-ao-cliente\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog da Casa Magalh\u00e3es\" \/>\n<meta property=\"article:published_time\" content=\"2020-08-04T13:22:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-08-06T20:07:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.casamagalhaes.com.br\/blog\/wp-content\/uploads\/2019\/02\/4-motivos-para-investir-no-treinamento-de-atendimento-ao-cliente.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"845\" \/>\n\t<meta property=\"og:image:height\" content=\"549\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Casa Magalh\u00e3es\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Casa Magalh\u00e3es\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.casamagalhaes.com.br\\\/blog\\\/gestao-de-empresas\\\/treinamento-de-atendimento-ao-cliente\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.casamagalhaes.com.br\\\/blog\\\/gestao-de-empresas\\\/treinamento-de-atendimento-ao-cliente\\\/\"},\"author\":{\"name\":\"Casa Magalh\u00e3es\",\"@id\":\"https:\\\/\\\/www.casamagalhaes.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/56c892544a618f4fc2031b11e7b05831\"},\"headline\":\"4 motivos para investir no treinamento de atendimento ao cliente!\",\"datePublished\":\"2020-08-04T13:22:00+00:00\",\"dateModified\":\"2020-08-06T20:07:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.casamagalhaes.com.br\\\/blog\\\/gestao-de-empresas\\\/treinamento-de-atendimento-ao-cliente\\\/\"},\"wordCount\":1229,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.casamagalhaes.com.br\\\/blog\\\/gestao-de-empresas\\\/treinamento-de-atendimento-ao-cliente\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.casamagalhaes.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/4-motivos-para-investir-no-treinamento-de-atendimento-ao-cliente.jpg\",\"keywords\":[\"Atendimento\",\"Gest\u00e3o de empresas\"],\"articleSection\":[\"Atendimento\",\"Gest\u00e3o de Empresas\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.casamagalhaes.com.br\\\/blog\\\/gestao-de-empresas\\\/treinamento-de-atendimento-ao-cliente\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.casamagalhaes.com.br\\\/blog\\\/gestao-de-empresas\\\/treinamento-de-atendimento-ao-cliente\\\/\",\"url\":\"https:\\\/\\\/www.casamagalhaes.com.br\\\/blog\\\/gestao-de-empresas\\\/treinamento-de-atendimento-ao-cliente\\\/\",\"name\":\"4 motivos para investir no treinamento de atendimento ao cliente!\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.casamagalhaes.com.br\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.casamagalhaes.com.br\\\/blog\\\/gestao-de-empresas\\\/treinamento-de-atendimento-ao-cliente\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.casamagalhaes.com.br\\\/blog\\\/gestao-de-empresas\\\/treinamento-de-atendimento-ao-cliente\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.casamagalhaes.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/4-motivos-para-investir-no-treinamento-de-atendimento-ao-cliente.jpg\",\"datePublished\":\"2020-08-04T13:22:00+00:00\",\"dateModified\":\"2020-08-06T20:07:03+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.casamagalhaes.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/56c892544a618f4fc2031b11e7b05831\"},\"description\":\"Voc\u00ea investe notreinamento de atendimento ao cliente da sua empresa? Confira os 4 motivos para investir nesse treinamento e a melhor forma de faz\u00ea-lo!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.casamagalhaes.com.br\\\/blog\\\/gestao-de-empresas\\\/treinamento-de-atendimento-ao-cliente\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.casamagalhaes.com.br\\\/blog\\\/gestao-de-empresas\\\/treinamento-de-atendimento-ao-cliente\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.casamagalhaes.com.br\\\/blog\\\/gestao-de-empresas\\\/treinamento-de-atendimento-ao-cliente\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.casamagalhaes.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/4-motivos-para-investir-no-treinamento-de-atendimento-ao-cliente.jpg\",\"contentUrl\":\"https:\\\/\\\/www.casamagalhaes.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/4-motivos-para-investir-no-treinamento-de-atendimento-ao-cliente.jpg\",\"width\":845,\"height\":549,\"caption\":\"4motivos para investir no treinamento de atendimento ao cliente\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.casamagalhaes.com.br\\\/blog\\\/gestao-de-empresas\\\/treinamento-de-atendimento-ao-cliente\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.casamagalhaes.com.br\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"4 motivos para investir no treinamento de atendimento ao cliente!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.casamagalhaes.com.br\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.casamagalhaes.com.br\\\/blog\\\/\",\"name\":\"Blog da Casa Magalh\u00e3es\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.casamagalhaes.com.br\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.casamagalhaes.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/56c892544a618f4fc2031b11e7b05831\",\"name\":\"Casa Magalh\u00e3es\",\"description\":\"Somos um Grupo empresarial da ind\u00fastria de TI, refer\u00eancia no mercado nacional de automa\u00e7\u00e3o comercial desde 1966, composto por empresas que desenvolvem softwares integrados de gest\u00e3o empresarial e frente de loja. Possui atendimento comercial, implanta\u00e7\u00e3o e suporte em todas as capitais do Brasil atrav\u00e9s de uma ampla rede de parceiros credenciados.\",\"sameAs\":[\"http:\\\/\\\/www.casamagalhaes.com.br\",\"https:\\\/\\\/www.instagram.com\\\/grupocasamagalhaes\\\/?hl=pt-br\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"4 motivos para investir no treinamento de atendimento ao cliente!","description":"Voc\u00ea investe notreinamento de atendimento ao cliente da sua empresa? Confira os 4 motivos para investir nesse treinamento e a melhor forma de faz\u00ea-lo!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.casamagalhaes.com.br\/blog\/gestao-de-empresas\/treinamento-de-atendimento-ao-cliente\/","og_locale":"pt_BR","og_type":"article","og_title":"4 motivos para investir no treinamento de atendimento ao cliente!","og_description":"Voc\u00ea investe notreinamento de atendimento ao cliente da sua empresa? Confira os 4 motivos para investir nesse treinamento e a melhor forma de faz\u00ea-lo!","og_url":"https:\/\/www.casamagalhaes.com.br\/blog\/gestao-de-empresas\/treinamento-de-atendimento-ao-cliente\/","og_site_name":"Blog da Casa Magalh\u00e3es","article_published_time":"2020-08-04T13:22:00+00:00","article_modified_time":"2020-08-06T20:07:03+00:00","og_image":[{"width":845,"height":549,"url":"https:\/\/www.casamagalhaes.com.br\/blog\/wp-content\/uploads\/2019\/02\/4-motivos-para-investir-no-treinamento-de-atendimento-ao-cliente.jpg","type":"image\/jpeg"}],"author":"Casa Magalh\u00e3es","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Casa Magalh\u00e3es","Est. tempo de leitura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.casamagalhaes.com.br\/blog\/gestao-de-empresas\/treinamento-de-atendimento-ao-cliente\/#article","isPartOf":{"@id":"https:\/\/www.casamagalhaes.com.br\/blog\/gestao-de-empresas\/treinamento-de-atendimento-ao-cliente\/"},"author":{"name":"Casa Magalh\u00e3es","@id":"https:\/\/www.casamagalhaes.com.br\/blog\/#\/schema\/person\/56c892544a618f4fc2031b11e7b05831"},"headline":"4 motivos para investir no treinamento de atendimento ao cliente!","datePublished":"2020-08-04T13:22:00+00:00","dateModified":"2020-08-06T20:07:03+00:00","mainEntityOfPage":{"@id":"https:\/\/www.casamagalhaes.com.br\/blog\/gestao-de-empresas\/treinamento-de-atendimento-ao-cliente\/"},"wordCount":1229,"commentCount":0,"image":{"@id":"https:\/\/www.casamagalhaes.com.br\/blog\/gestao-de-empresas\/treinamento-de-atendimento-ao-cliente\/#primaryimage"},"thumbnailUrl":"https:\/\/www.casamagalhaes.com.br\/blog\/wp-content\/uploads\/2019\/02\/4-motivos-para-investir-no-treinamento-de-atendimento-ao-cliente.jpg","keywords":["Atendimento","Gest\u00e3o de empresas"],"articleSection":["Atendimento","Gest\u00e3o de Empresas"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.casamagalhaes.com.br\/blog\/gestao-de-empresas\/treinamento-de-atendimento-ao-cliente\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.casamagalhaes.com.br\/blog\/gestao-de-empresas\/treinamento-de-atendimento-ao-cliente\/","url":"https:\/\/www.casamagalhaes.com.br\/blog\/gestao-de-empresas\/treinamento-de-atendimento-ao-cliente\/","name":"4 motivos para investir no treinamento de atendimento ao cliente!","isPartOf":{"@id":"https:\/\/www.casamagalhaes.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.casamagalhaes.com.br\/blog\/gestao-de-empresas\/treinamento-de-atendimento-ao-cliente\/#primaryimage"},"image":{"@id":"https:\/\/www.casamagalhaes.com.br\/blog\/gestao-de-empresas\/treinamento-de-atendimento-ao-cliente\/#primaryimage"},"thumbnailUrl":"https:\/\/www.casamagalhaes.com.br\/blog\/wp-content\/uploads\/2019\/02\/4-motivos-para-investir-no-treinamento-de-atendimento-ao-cliente.jpg","datePublished":"2020-08-04T13:22:00+00:00","dateModified":"2020-08-06T20:07:03+00:00","author":{"@id":"https:\/\/www.casamagalhaes.com.br\/blog\/#\/schema\/person\/56c892544a618f4fc2031b11e7b05831"},"description":"Voc\u00ea investe notreinamento de atendimento ao cliente da sua empresa? Confira os 4 motivos para investir nesse treinamento e a melhor forma de faz\u00ea-lo!","breadcrumb":{"@id":"https:\/\/www.casamagalhaes.com.br\/blog\/gestao-de-empresas\/treinamento-de-atendimento-ao-cliente\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.casamagalhaes.com.br\/blog\/gestao-de-empresas\/treinamento-de-atendimento-ao-cliente\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.casamagalhaes.com.br\/blog\/gestao-de-empresas\/treinamento-de-atendimento-ao-cliente\/#primaryimage","url":"https:\/\/www.casamagalhaes.com.br\/blog\/wp-content\/uploads\/2019\/02\/4-motivos-para-investir-no-treinamento-de-atendimento-ao-cliente.jpg","contentUrl":"https:\/\/www.casamagalhaes.com.br\/blog\/wp-content\/uploads\/2019\/02\/4-motivos-para-investir-no-treinamento-de-atendimento-ao-cliente.jpg","width":845,"height":549,"caption":"4motivos para investir no treinamento de atendimento ao cliente"},{"@type":"BreadcrumbList","@id":"https:\/\/www.casamagalhaes.com.br\/blog\/gestao-de-empresas\/treinamento-de-atendimento-ao-cliente\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.casamagalhaes.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"4 motivos para investir no treinamento de atendimento ao cliente!"}]},{"@type":"WebSite","@id":"https:\/\/www.casamagalhaes.com.br\/blog\/#website","url":"https:\/\/www.casamagalhaes.com.br\/blog\/","name":"Blog da Casa Magalh\u00e3es","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.casamagalhaes.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/www.casamagalhaes.com.br\/blog\/#\/schema\/person\/56c892544a618f4fc2031b11e7b05831","name":"Casa Magalh\u00e3es","description":"Somos um Grupo empresarial da ind\u00fastria de TI, refer\u00eancia no mercado nacional de automa\u00e7\u00e3o comercial desde 1966, composto por empresas que desenvolvem softwares integrados de gest\u00e3o empresarial e frente de loja. Possui atendimento comercial, implanta\u00e7\u00e3o e suporte em todas as capitais do Brasil atrav\u00e9s de uma ampla rede de parceiros credenciados.","sameAs":["http:\/\/www.casamagalhaes.com.br","https:\/\/www.instagram.com\/grupocasamagalhaes\/?hl=pt-br"]}]}},"_links":{"self":[{"href":"https:\/\/www.casamagalhaes.com.br\/blog\/wp-json\/wp\/v2\/posts\/4995","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.casamagalhaes.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.casamagalhaes.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.casamagalhaes.com.br\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.casamagalhaes.com.br\/blog\/wp-json\/wp\/v2\/comments?post=4995"}],"version-history":[{"count":12,"href":"https:\/\/www.casamagalhaes.com.br\/blog\/wp-json\/wp\/v2\/posts\/4995\/revisions"}],"predecessor-version":[{"id":7621,"href":"https:\/\/www.casamagalhaes.com.br\/blog\/wp-json\/wp\/v2\/posts\/4995\/revisions\/7621"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.casamagalhaes.com.br\/blog\/wp-json\/wp\/v2\/media\/4999"}],"wp:attachment":[{"href":"https:\/\/www.casamagalhaes.com.br\/blog\/wp-json\/wp\/v2\/media?parent=4995"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.casamagalhaes.com.br\/blog\/wp-json\/wp\/v2\/categories?post=4995"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.casamagalhaes.com.br\/blog\/wp-json\/wp\/v2\/tags?post=4995"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}