{"id":4266,"date":"2018-09-13T14:08:44","date_gmt":"2018-09-13T17:08:44","guid":{"rendered":"https:\/\/www.casamagalhaes.com.br\/blog\/?p=4266"},"modified":"2018-10-22T08:49:29","modified_gmt":"2018-10-22T11:49:29","slug":"ebook-gratuito-acoes-promocionais-no-pdv","status":"publish","type":"post","link":"https:\/\/www.casamagalhaes.com.br\/blog\/marketing\/ebook-gratuito-acoes-promocionais-no-pdv\/","title":{"rendered":"[Material Gratuito] A\u00e7\u00f5es promocionais no PDV"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">\u201cUma mente que se abre a uma nova ideia jamais volta ao seu tamanho original.\u201d <\/span><span style=\"font-weight: 400;\">\u00a0Essa \u00e9 uma frase bastante conhecida do Albert Einsten, a escolhi para abrir este conte\u00fado sobre: <\/span><b>A\u00e7\u00f5es promocionais no PDV &#8211; Estrat\u00e9gias para engajar sua equipe, <\/b><span style=\"font-weight: 400;\">pois acredito que assim seja a mente de um empreendedor, \u201caberta a novas ideias\u2019, estou certa?<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Mas ser aberto a novas ideias n\u00e3o \u00e9 tudo! <strong>No mundo dos neg\u00f3cios estar preparado \u00e9 primordial para n\u00e3o correr risco de perder as oportunidades<\/strong>. \u00c9 preciso procurar alternativas para<a href=\"https:\/\/www.casamagalhaes.com.br\/blog\/marketing\/supermercado-no-sao-joao\/\"> gerar novas vendas<\/a>, \u00a0por isso, eu preparei esse material pra voc\u00ea: <\/span>A\u00e7\u00f5es promocionais no PDV &#8211; Estrat\u00e9gias para engajar sua equipe.<\/p>\n<p>Acredito que para sermos um <a href=\"https:\/\/www.casamagalhaes.com.br\/blog\/empreendedorismo\/dicas-empreendedor-de-sucesso\/\">empreendedor<\/a> e l\u00edder de sucesso, al\u00e9m de desenvolvermos boas ideias, devemos ser capazes de vend\u00ea-las. E desafio maior ainda: conseguirmos que elas sejam compradas! No dia a dia de trabalho lidamos com pessoas, tanto as que desejam comprar nossos produtos quanto a equipe interna de colaboradores que nos ajudam nas opera\u00e7\u00f5es do neg\u00f3cio.<\/p>\n<p>Agora eu te pergunto: <strong>Como anda a motiva\u00e7\u00e3o da sua equipe? Seus colaboradores compram as suas ideias?<\/strong><\/p>\n<p>Bom, a resposta voc\u00ea sabe melhor do que eu. Mas n\u00e3o se preocupe que esse material tamb\u00e9m foi desenvolvido com o intuito de tra\u00e7ar estrat\u00e9gias para manter seu time alinhando e satisfeito no ambiente de trabalho. E melhor ainda! Contribuindo para o sucesso nas vendas.<\/p>\n<p>Ao longo da leitura do ebook, voc\u00ea vai se deparar muito com a palavra <b>Oportunidade<\/b>, pois, mais que estrat\u00e9gias de marketing, estruturar bem seu ponto de venda\u00a0\u00e9 uma estrat\u00e9gia de oportunidades.\u00a0 \u00c9 um material completo que al\u00e9m de tirar suas principais d\u00favidas sobre <a href=\"https:\/\/www.casamagalhaes.com.br\/blog\/financas\/promocao-margem-de-lucro\/\">a\u00e7\u00f5es promocionais<\/a> no PDV, vai\u00a0trazer\u00a0 muitos<em> insights<\/em> que podem ser aplicados em sua empresa.<\/p>\n<h3><strong>O que o ebook A\u00e7\u00f5es Promocionais no PDV pode fazer pelo seu neg\u00f3cio<\/strong><\/h3>\n<ul>\n<li>Entender a import\u00e2ncia do PDV para o varejo<\/li>\n<li>Apresentar conceitos e diferencia\u00e7\u00e3o de Visual Merchandising e Cross Merchandising<\/li>\n<li>Estrat\u00e9gias promocionais para gerar lucro e engajar a sua equipe de vendas<\/li>\n<li>Cases de sucesso e muito mais<\/li>\n<\/ul>\n<p>Fa\u00e7a o download gratuito do material e veja as suas vendas crescerem!<\/p>\n<p><a target=\"_blank\" href=\"https:\/\/conteudo.casamagalhaes.com.br\/ebook-acoes-promocionais-no-pdv?utm_source=blog&amp;utm_medium=post&amp;utm_campaign=artigo-ebook-acoes-pdv\"><img loading=\"lazy\" decoding=\"async\" width=\"845\" height=\"200\" class=\"img-responsive size-full wp-image-4273 alignleft\" src=\"https:\/\/www.casamagalhaes.com.br\/blog\/wp-content\/uploads\/2018\/09\/Banner-CTA-blog.jpg\" alt=\"Banner CTA blog\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Conhe\u00e7a as principais a\u00e7\u00f5es promocionais no PDV e descubra estrat\u00e9gias para manter a equipe de vendas engajada! <\/p>\n","protected":false},"author":3,"featured_media":4276,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"episode_type":"","audio_file":"","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","itunes_episode_number":"","itunes_title":"","itunes_season_number":"","itunes_episode_type":"","ngg_post_thumbnail":0,"footnotes":""},"categories":[157,164],"tags":[200],"class_list":["post-4266","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-marketing","category-vendas","tag-material-gratuito"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ebook Gratuito - A\u00e7\u00f5es Promocionais no PDV<\/title>\n<meta name=\"description\" content=\"Conhe\u00e7a as principais a\u00e7\u00f5es promocionais no PDV e saiba como manter sua equipe de vendas engajada. Acesse o material gratuito!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.casamagalhaes.com.br\/blog\/marketing\/ebook-gratuito-acoes-promocionais-no-pdv\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ebook Gratuito - A\u00e7\u00f5es Promocionais no PDV\" \/>\n<meta property=\"og:description\" content=\"Conhe\u00e7a as principais a\u00e7\u00f5es promocionais no PDV e saiba como manter sua equipe de vendas engajada. Acesse o material gratuito!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.casamagalhaes.com.br\/blog\/marketing\/ebook-gratuito-acoes-promocionais-no-pdv\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog da Casa Magalh\u00e3es\" \/>\n<meta property=\"article:published_time\" content=\"2018-09-13T17:08:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-10-22T11:49:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.casamagalhaes.com.br\/blog\/wp-content\/uploads\/2018\/09\/a\u00e7\u00f5es-promocionais-no-pdv-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"845\" \/>\n\t<meta property=\"og:image:height\" content=\"549\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Casa Magalh\u00e3es\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Casa Magalh\u00e3es\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.casamagalhaes.com.br\\\/blog\\\/marketing\\\/ebook-gratuito-acoes-promocionais-no-pdv\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.casamagalhaes.com.br\\\/blog\\\/marketing\\\/ebook-gratuito-acoes-promocionais-no-pdv\\\/\"},\"author\":{\"name\":\"Casa Magalh\u00e3es\",\"@id\":\"https:\\\/\\\/www.casamagalhaes.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/56c892544a618f4fc2031b11e7b05831\"},\"headline\":\"[Material Gratuito] A\u00e7\u00f5es promocionais no PDV\",\"datePublished\":\"2018-09-13T17:08:44+00:00\",\"dateModified\":\"2018-10-22T11:49:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.casamagalhaes.com.br\\\/blog\\\/marketing\\\/ebook-gratuito-acoes-promocionais-no-pdv\\\/\"},\"wordCount\":378,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.casamagalhaes.com.br\\\/blog\\\/marketing\\\/ebook-gratuito-acoes-promocionais-no-pdv\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.casamagalhaes.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/a\u00e7\u00f5es-promocionais-no-pdv-1.jpg\",\"keywords\":[\"Material Gratuito\"],\"articleSection\":[\"Marketing\",\"Vendas\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.casamagalhaes.com.br\\\/blog\\\/marketing\\\/ebook-gratuito-acoes-promocionais-no-pdv\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.casamagalhaes.com.br\\\/blog\\\/marketing\\\/ebook-gratuito-acoes-promocionais-no-pdv\\\/\",\"url\":\"https:\\\/\\\/www.casamagalhaes.com.br\\\/blog\\\/marketing\\\/ebook-gratuito-acoes-promocionais-no-pdv\\\/\",\"name\":\"Ebook Gratuito - A\u00e7\u00f5es Promocionais no PDV\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.casamagalhaes.com.br\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.casamagalhaes.com.br\\\/blog\\\/marketing\\\/ebook-gratuito-acoes-promocionais-no-pdv\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.casamagalhaes.com.br\\\/blog\\\/marketing\\\/ebook-gratuito-acoes-promocionais-no-pdv\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.casamagalhaes.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/a\u00e7\u00f5es-promocionais-no-pdv-1.jpg\",\"datePublished\":\"2018-09-13T17:08:44+00:00\",\"dateModified\":\"2018-10-22T11:49:29+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.casamagalhaes.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/56c892544a618f4fc2031b11e7b05831\"},\"description\":\"Conhe\u00e7a as principais a\u00e7\u00f5es promocionais no PDV e saiba como manter sua equipe de vendas engajada. Acesse o material gratuito!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.casamagalhaes.com.br\\\/blog\\\/marketing\\\/ebook-gratuito-acoes-promocionais-no-pdv\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.casamagalhaes.com.br\\\/blog\\\/marketing\\\/ebook-gratuito-acoes-promocionais-no-pdv\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.casamagalhaes.com.br\\\/blog\\\/marketing\\\/ebook-gratuito-acoes-promocionais-no-pdv\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.casamagalhaes.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/a\u00e7\u00f5es-promocionais-no-pdv-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.casamagalhaes.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/a\u00e7\u00f5es-promocionais-no-pdv-1.jpg\",\"width\":845,\"height\":549},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.casamagalhaes.com.br\\\/blog\\\/marketing\\\/ebook-gratuito-acoes-promocionais-no-pdv\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.casamagalhaes.com.br\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"[Material Gratuito] A\u00e7\u00f5es promocionais no PDV\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.casamagalhaes.com.br\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.casamagalhaes.com.br\\\/blog\\\/\",\"name\":\"Blog da Casa Magalh\u00e3es\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.casamagalhaes.com.br\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.casamagalhaes.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/56c892544a618f4fc2031b11e7b05831\",\"name\":\"Casa Magalh\u00e3es\",\"description\":\"Somos um Grupo empresarial da ind\u00fastria de TI, refer\u00eancia no mercado nacional de automa\u00e7\u00e3o comercial desde 1966, composto por empresas que desenvolvem softwares integrados de gest\u00e3o empresarial e frente de loja. Possui atendimento comercial, implanta\u00e7\u00e3o e suporte em todas as capitais do Brasil atrav\u00e9s de uma ampla rede de parceiros credenciados.\",\"sameAs\":[\"http:\\\/\\\/www.casamagalhaes.com.br\",\"https:\\\/\\\/www.instagram.com\\\/grupocasamagalhaes\\\/?hl=pt-br\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ebook Gratuito - A\u00e7\u00f5es Promocionais no PDV","description":"Conhe\u00e7a as principais a\u00e7\u00f5es promocionais no PDV e saiba como manter sua equipe de vendas engajada. Acesse o material gratuito!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.casamagalhaes.com.br\/blog\/marketing\/ebook-gratuito-acoes-promocionais-no-pdv\/","og_locale":"pt_BR","og_type":"article","og_title":"Ebook Gratuito - A\u00e7\u00f5es Promocionais no PDV","og_description":"Conhe\u00e7a as principais a\u00e7\u00f5es promocionais no PDV e saiba como manter sua equipe de vendas engajada. Acesse o material gratuito!","og_url":"https:\/\/www.casamagalhaes.com.br\/blog\/marketing\/ebook-gratuito-acoes-promocionais-no-pdv\/","og_site_name":"Blog da Casa Magalh\u00e3es","article_published_time":"2018-09-13T17:08:44+00:00","article_modified_time":"2018-10-22T11:49:29+00:00","og_image":[{"width":845,"height":549,"url":"https:\/\/www.casamagalhaes.com.br\/blog\/wp-content\/uploads\/2018\/09\/a\u00e7\u00f5es-promocionais-no-pdv-1.jpg","type":"image\/jpeg"}],"author":"Casa Magalh\u00e3es","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Casa Magalh\u00e3es","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.casamagalhaes.com.br\/blog\/marketing\/ebook-gratuito-acoes-promocionais-no-pdv\/#article","isPartOf":{"@id":"https:\/\/www.casamagalhaes.com.br\/blog\/marketing\/ebook-gratuito-acoes-promocionais-no-pdv\/"},"author":{"name":"Casa Magalh\u00e3es","@id":"https:\/\/www.casamagalhaes.com.br\/blog\/#\/schema\/person\/56c892544a618f4fc2031b11e7b05831"},"headline":"[Material Gratuito] A\u00e7\u00f5es promocionais no PDV","datePublished":"2018-09-13T17:08:44+00:00","dateModified":"2018-10-22T11:49:29+00:00","mainEntityOfPage":{"@id":"https:\/\/www.casamagalhaes.com.br\/blog\/marketing\/ebook-gratuito-acoes-promocionais-no-pdv\/"},"wordCount":378,"commentCount":0,"image":{"@id":"https:\/\/www.casamagalhaes.com.br\/blog\/marketing\/ebook-gratuito-acoes-promocionais-no-pdv\/#primaryimage"},"thumbnailUrl":"https:\/\/www.casamagalhaes.com.br\/blog\/wp-content\/uploads\/2018\/09\/a\u00e7\u00f5es-promocionais-no-pdv-1.jpg","keywords":["Material Gratuito"],"articleSection":["Marketing","Vendas"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.casamagalhaes.com.br\/blog\/marketing\/ebook-gratuito-acoes-promocionais-no-pdv\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.casamagalhaes.com.br\/blog\/marketing\/ebook-gratuito-acoes-promocionais-no-pdv\/","url":"https:\/\/www.casamagalhaes.com.br\/blog\/marketing\/ebook-gratuito-acoes-promocionais-no-pdv\/","name":"Ebook Gratuito - A\u00e7\u00f5es Promocionais no PDV","isPartOf":{"@id":"https:\/\/www.casamagalhaes.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.casamagalhaes.com.br\/blog\/marketing\/ebook-gratuito-acoes-promocionais-no-pdv\/#primaryimage"},"image":{"@id":"https:\/\/www.casamagalhaes.com.br\/blog\/marketing\/ebook-gratuito-acoes-promocionais-no-pdv\/#primaryimage"},"thumbnailUrl":"https:\/\/www.casamagalhaes.com.br\/blog\/wp-content\/uploads\/2018\/09\/a\u00e7\u00f5es-promocionais-no-pdv-1.jpg","datePublished":"2018-09-13T17:08:44+00:00","dateModified":"2018-10-22T11:49:29+00:00","author":{"@id":"https:\/\/www.casamagalhaes.com.br\/blog\/#\/schema\/person\/56c892544a618f4fc2031b11e7b05831"},"description":"Conhe\u00e7a as principais a\u00e7\u00f5es promocionais no PDV e saiba como manter sua equipe de vendas engajada. Acesse o material gratuito!","breadcrumb":{"@id":"https:\/\/www.casamagalhaes.com.br\/blog\/marketing\/ebook-gratuito-acoes-promocionais-no-pdv\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.casamagalhaes.com.br\/blog\/marketing\/ebook-gratuito-acoes-promocionais-no-pdv\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.casamagalhaes.com.br\/blog\/marketing\/ebook-gratuito-acoes-promocionais-no-pdv\/#primaryimage","url":"https:\/\/www.casamagalhaes.com.br\/blog\/wp-content\/uploads\/2018\/09\/a\u00e7\u00f5es-promocionais-no-pdv-1.jpg","contentUrl":"https:\/\/www.casamagalhaes.com.br\/blog\/wp-content\/uploads\/2018\/09\/a\u00e7\u00f5es-promocionais-no-pdv-1.jpg","width":845,"height":549},{"@type":"BreadcrumbList","@id":"https:\/\/www.casamagalhaes.com.br\/blog\/marketing\/ebook-gratuito-acoes-promocionais-no-pdv\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.casamagalhaes.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"[Material Gratuito] A\u00e7\u00f5es promocionais no PDV"}]},{"@type":"WebSite","@id":"https:\/\/www.casamagalhaes.com.br\/blog\/#website","url":"https:\/\/www.casamagalhaes.com.br\/blog\/","name":"Blog da Casa Magalh\u00e3es","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.casamagalhaes.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/www.casamagalhaes.com.br\/blog\/#\/schema\/person\/56c892544a618f4fc2031b11e7b05831","name":"Casa Magalh\u00e3es","description":"Somos um Grupo empresarial da ind\u00fastria de TI, refer\u00eancia no mercado nacional de automa\u00e7\u00e3o comercial desde 1966, composto por empresas que desenvolvem softwares integrados de gest\u00e3o empresarial e frente de loja. Possui atendimento comercial, implanta\u00e7\u00e3o e suporte em todas as capitais do Brasil atrav\u00e9s de uma ampla rede de parceiros credenciados.","sameAs":["http:\/\/www.casamagalhaes.com.br","https:\/\/www.instagram.com\/grupocasamagalhaes\/?hl=pt-br"]}]}},"_links":{"self":[{"href":"https:\/\/www.casamagalhaes.com.br\/blog\/wp-json\/wp\/v2\/posts\/4266","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.casamagalhaes.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.casamagalhaes.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.casamagalhaes.com.br\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.casamagalhaes.com.br\/blog\/wp-json\/wp\/v2\/comments?post=4266"}],"version-history":[{"count":10,"href":"https:\/\/www.casamagalhaes.com.br\/blog\/wp-json\/wp\/v2\/posts\/4266\/revisions"}],"predecessor-version":[{"id":4281,"href":"https:\/\/www.casamagalhaes.com.br\/blog\/wp-json\/wp\/v2\/posts\/4266\/revisions\/4281"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.casamagalhaes.com.br\/blog\/wp-json\/wp\/v2\/media\/4276"}],"wp:attachment":[{"href":"https:\/\/www.casamagalhaes.com.br\/blog\/wp-json\/wp\/v2\/media?parent=4266"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.casamagalhaes.com.br\/blog\/wp-json\/wp\/v2\/categories?post=4266"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.casamagalhaes.com.br\/blog\/wp-json\/wp\/v2\/tags?post=4266"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}