{"id":3329,"date":"2019-04-22T15:30:35","date_gmt":"2019-04-22T18:30:35","guid":{"rendered":"https:\/\/www.casamagalhaes.com.br\/blog\/?p=3329"},"modified":"2020-02-27T18:11:00","modified_gmt":"2020-02-27T21:11:00","slug":"reduzir-o-desperdicio-no-restaurante","status":"publish","type":"post","link":"https:\/\/www.casamagalhaes.com.br\/blog\/bares-e-restaurantes\/reduzir-o-desperdicio-no-restaurante\/","title":{"rendered":"Como reduzir o desperd\u00edcio no restaurante com essas 7 dicas"},"content":{"rendered":"\n<p><span style=\"font-weight: 400;\">Oferecer um produto de qualidade com redu\u00e7\u00e3o dos custos e despesas. Essa parece ser uma regra e um grande desafio de qualquer empreendedor. Em se tratando do ramo de <\/span><i><span style=\"font-weight: 400;\">food service<\/span><\/i><span style=\"font-weight: 400;\">, o maior desafio \u00e9 reduzir o desperd\u00edcio no restaurante.<\/span><\/p>\n\n\n\n<p><span style=\"font-weight: 400;\">De acordo com a revista <\/span><a href=\"https:\/\/www.foodmagazine.com.br\/home\"><span style=\"font-weight: 400;\">Food Magazine<\/span><\/a><span style=\"font-weight: 400;\">, cerca de 10% de todos os ingredientes utilizados em restaurantes v\u00e3o parar na lixeira. Este cen\u00e1rio de perdas \u00e9 gerado por uma s\u00e9rie de h\u00e1bitos viciosos na produ\u00e7\u00e3o dos restaurantes, que v\u00e3o desde a compra de insumos at\u00e9 o consumo &nbsp;final.<\/span><\/p>\n\n\n\n<p><span style=\"font-weight: 400;\">Se voc\u00ea n\u00e3o quer cometer esses <\/span><a href=\"https:\/\/www.casamagalhaes.com.br\/blog\/bares-e-restaurantes\/erros-acabar-com-restaurante\/\"><span style=\"font-weight: 400;\">erros<\/span><\/a><span style=\"font-weight: 400;\">, continue lendo e confira <\/span><b>7 a\u00e7\u00f5es que ajudar\u00e3o a reduzir o desperd\u00edcio no restaurante<\/b><span style=\"font-weight: 400;\">:<\/span><\/p>\n\n\n\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_83 counter-hierarchy ez-toc-counter ez-toc-light-blue ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Navegue pelo conte\u00fado<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Alternar tabela de conte\u00fado\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/www.casamagalhaes.com.br\/blog\/bares-e-restaurantes\/reduzir-o-desperdicio-no-restaurante\/#1_Crie_fichas_tecnicas_para_cada_prato\" >1. Crie fichas t\u00e9cnicas para cada prato<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/www.casamagalhaes.com.br\/blog\/bares-e-restaurantes\/reduzir-o-desperdicio-no-restaurante\/#2_Planeje_a_apresentacao_dos_pratos\" >2. Planeje a apresenta\u00e7\u00e3o dos pratos<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/www.casamagalhaes.com.br\/blog\/bares-e-restaurantes\/reduzir-o-desperdicio-no-restaurante\/#3_Produza_apenas_o_necessario\" >3. Produza apenas o necess\u00e1rio<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/www.casamagalhaes.com.br\/blog\/bares-e-restaurantes\/reduzir-o-desperdicio-no-restaurante\/#4_Faca_uma_boa_gestao_de_compras\" >4. Fa\u00e7a uma boa gest\u00e3o de compras<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/www.casamagalhaes.com.br\/blog\/bares-e-restaurantes\/reduzir-o-desperdicio-no-restaurante\/#5_Armazene_bem_os_seus_insumos\" >5. Armazene bem os seus insumos<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/www.casamagalhaes.com.br\/blog\/bares-e-restaurantes\/reduzir-o-desperdicio-no-restaurante\/#6_Evite_erros_operacionais\" >6. Evite erros operacionais<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/www.casamagalhaes.com.br\/blog\/bares-e-restaurantes\/reduzir-o-desperdicio-no-restaurante\/#7_Use_tecnologia_para_reduzir_o_desperdicio_de_alimentos\" >7. Use tecnologia para reduzir o desperd\u00edcio de alimentos<\/a><\/li><\/ul><\/nav><\/div>\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"1_Crie_fichas_tecnicas_para_cada_prato\"><\/span><b>1. Crie fichas t\u00e9cnicas para cada prato<\/b><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p><span style=\"font-weight: 400;\">A primeira dica \u00e9: comece controlando os desperd\u00edcios desde a produ\u00e7\u00e3o dos alimentos. Voc\u00ea pode fazer isso por meio de <a target=\"_blank\" href=\"https:\/\/www.casamagalhaes.com.br\/blog\/bares-e-restaurantes\/conheca-a-ficha-tecnica-para-restaurantes\/\" rel=\"noopener noreferrer\">fichas t\u00e9cnicas<\/a>, que s\u00e3o como registros que guardam todas as informa\u00e7\u00f5es dos pratos servidos no restaurante.<\/span><\/p>\n\n\n\n<p><span style=\"font-weight: 400;\">Utilizando esse recurso \u00e9 poss\u00edvel padronizar n\u00e3o s\u00f3 o sabor, mas tamb\u00e9m o custo de cada receita e o tamanho da por\u00e7\u00e3o, controlando o rendimento de cada ingrediente. Al\u00e9m de tamb\u00e9m proporcionar uma fonte segura que serve de base no momento de definir o pre\u00e7o final do prato.<\/span><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"2_Planeje_a_apresentacao_dos_pratos\"><\/span><b>2. Planeje a apresenta\u00e7\u00e3o dos pratos<\/b><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p><span style=\"font-weight: 400;\">N\u00f3s sabemos que boa parte do apelo de vendas de um <\/span><i><span style=\"font-weight: 400;\">food service<\/span><\/i><span style=\"font-weight: 400;\"> est\u00e1 na apresenta\u00e7\u00e3o dos pratos. Os clientes \u201ccomem com os olhos\u201d e por isso, os restaurantes exageram na quantidade de alimentos servida para atrair a aten\u00e7\u00e3o do consumidor e aumentar as vendas.<\/span><\/p>\n\n\n\n<p><span style=\"font-weight: 400;\">Entretanto, esse tipo de \u201cmerchandising\u201d acaba gerando preju\u00edzos para o estabelecimento por n\u00e3o possuir uma padroniza\u00e7\u00e3o das por\u00e7\u00f5es e contribuindo para o desperd\u00edcio, caso o cliente n\u00e3o consuma toda a refei\u00e7\u00e3o.<\/span><\/p>\n\n\n\n<p><span style=\"font-weight: 400;\">Para n\u00e3o abrir m\u00e3o de uma apresenta\u00e7\u00e3o atraente, \u00e9 necess\u00e1ria uma boa dose de criatividade para utilizar menos ingredientes sem perder a est\u00e9tica dos pratos.<\/span><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"3_Produza_apenas_o_necessario\"><\/span><b>3. Produza apenas o necess\u00e1rio<\/b><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p><span style=\"font-weight: 400;\">Ficar sem um determinado item do card\u00e1pio \u00e9 uma situa\u00e7\u00e3o chata e que pode gerar insatisfa\u00e7\u00e3o nos clientes. Garantir que o cliente tenha todos os produtos dispon\u00edveis at\u00e9 a hora de fechar o estabelecimento, n\u00e3o significa exceder na produ\u00e7\u00e3o dos preparos, mesmo que n\u00e3o haja pedido para eles.<\/span><\/p>\n\n\n\n<p><span style=\"font-weight: 400;\">Produ\u00e7\u00f5es em larga escala costumam ser sin\u00f4nimo de otimiza\u00e7\u00e3o do tempo de trabalho. Pensando desta forma, muitos donos de restaurantes optam pelo preparo de alimentos em grandes lotes para minimizar os custos com sal\u00e1rios e horas extras.<\/span><\/p>\n\n\n\n<p><span style=\"font-weight: 400;\">Entretanto, este tipo de produ\u00e7\u00e3o costuma ser inflex\u00edvel quanto a real demanda do estabelecimento e claro, n\u00e3o ajuda a reduzir o desperd\u00edcio no restaurante. Estudos da UNEP em parceria com o <\/span><a href=\"https:\/\/www.rj.senac.br\/\"><span style=\"font-weight: 400;\">SENAC\/RJ<\/span><\/a><span style=\"font-weight: 400;\"> apontam que o processo de produ\u00e7\u00e3o \u00e9 respons\u00e1vel por 80% do desperd\u00edcio de alimentos nas empresas de <\/span><i><span style=\"font-weight: 400;\">food service<\/span><\/i><span style=\"font-weight: 400;\">.<\/span><\/p>\n\n\n\n<p><span style=\"font-weight: 400;\">Se voc\u00ea adota essa pr\u00e1tica no seu estabelecimento \u00e9 necess\u00e1rio refletir se a economia gerada na diminui\u00e7\u00e3o do tempo de trabalho \u00e9 relevante quando comparado ao descarte de insumos gerados pela produ\u00e7\u00e3o em grande escala.<\/span><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"4_Faca_uma_boa_gestao_de_compras\"><\/span><b>4. Fa\u00e7a uma boa gest\u00e3o de compras<\/b><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p><span style=\"font-weight: 400;\">Alimentos que se deterioram rapidamente como frutas, verduras, latic\u00ednios e temperos devem ser comprados aos poucos, assim voc\u00ea evita que eles estraguem e, consequentemente, o desperd\u00edcio de alimentos e de dinheiro.<\/span><\/p>\n\n\n\n<p><span style=\"font-weight: 400;\">O melhor <\/span><a href=\"https:\/\/www.casamagalhaes.com.br\/blog\/gestao-de-empresas\/gestao-de-fornecedores-e-importante\/\"><span style=\"font-weight: 400;\">fornecedor<\/span><\/a><span style=\"font-weight: 400;\"> \u00e9 aquele que oferece os produtos mais frescos e de qualidade; te deixa a par das safras e da validade dos produtos e que n\u00e3o falha nos compromissos.<\/span><\/p>\n\n\n\n<p><span style=\"font-weight: 400;\">\u00c9 importante voc\u00ea conhecer o giro de cada produto, calcular o estoque de seguran\u00e7a e conhecer as suas sazonalidades.<\/span><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"5_Armazene_bem_os_seus_insumos\"><\/span><b>5. Armazene bem os seus insumos<\/b><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p><span style=\"font-weight: 400;\">O <a href=\"https:\/\/www.casamagalhaes.com.br\/blog\/gestao-de-estoque\/gestao-de-estoque\/\">controle de estoque<\/a> faz toda a diferen\u00e7a na hora de evitar desperd\u00edcios de alimentos. Mantenha-o reduzido. Voc\u00ea corre mais riscos de perdas quando o n\u00edvel do estoque est\u00e1 alto.<\/span><\/p>\n\n\n\n<p><span style=\"font-weight: 400;\">Mercadorias vencidas, estoque sendo descartado e produtos sumindo das prateleiras. Se isso soa familiar, saiba que parte do desperd\u00edcio pode estar sendo gerado pelo armazenamento inadequado dos insumos. Algumas boas pr\u00e1ticas podem ajud\u00e1-lo a diminuir esses problemas e reduzir o custo do seu estoque.<\/span><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">Procure manter as embalagens originais dos produtos, elas foram desenvolvidas para preservar os alimentos e aumentar a durabilidade das mesmas;<\/span><\/li><li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">Respeite sempre o empilhamento m\u00e1ximo descrito nas caixas das mercadorias;<\/span><\/li><li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">Fique atento a necessidade de refrigera\u00e7\u00e3o. O armazenamento desnecess\u00e1rio de alguns alimentos pode afetar as caracter\u00edsticas originais e gerar custos.<\/span><\/li><li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">Reserve um hor\u00e1rio espec\u00edfico para o recebimento e armazenagem dos insumos;<\/span><\/li><li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">Os alimentos industrializados devem ser separados dos gr\u00e3os e cereais para evitar infesta\u00e7\u00e3o de insetos;<\/span><\/li><li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">Organize os insumos de acordo com a data de validade, de forma que os produtos com vencimento pr\u00f3ximo sejam consumidos antes;<\/span><\/li><\/ul>\n\n\n\n<p><span style=\"font-weight: 400;\">\u00c9 atrav\u00e9s do <a href=\"https:\/\/www.casamagalhaes.com.br\/blog\/gestao-de-estoque\/gestao-de-estoque\/\">controle de estoque<\/a> que voc\u00ea conseguir\u00e1 tomar decis\u00f5es sobre os produtos que est\u00e3o faltando ou encalhados, definindo a import\u00e2ncia de cada ingrediente no seu restaurante.<\/span><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><a href=\"http:\/\/conteudo.casamagalhaes.com.br\/e-book-controle-de-pereciveis?utm_source=blog&amp;utm_medium=post&amp;utm_campaign=mg%20controle%20de%20pereciveis\"><img loading=\"lazy\" decoding=\"async\" width=\"845\" height=\"200\" src=\"https:\/\/www.casamagalhaes.com.br\/blog\/wp-content\/uploads\/2019\/01\/controle-de-estoque-de-pereciveis.png\" alt=\"como reduzir o desperd\u00edcio no restaurante\" class=\"wp-image-4848\"\/><\/a><\/figure><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"6_Evite_erros_operacionais\"><\/span><b>6. Evite erros operacionais<\/b><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p><span style=\"font-weight: 400;\">Os erros operacionais no momento da venda ou do preparo s\u00e3o, sem d\u00favidas, uma das grandes causas de desperd\u00edcio.<\/span><\/p>\n\n\n\n<p><span style=\"font-weight: 400;\">Se o gar\u00e7om anota o pedido errado, a cozinha ir\u00e1 gastar tempo e ingrediente preparando algo que n\u00e3o ser\u00e1 consumido, logo o trabalho ser\u00e1 refeito e voc\u00ea dever\u00e1 cobrar apenas pelo pedido correto. O mesmo acontece se houver algum erro durante a sua execu\u00e7\u00e3o.<\/span><\/p>\n\n\n\n<p><span style=\"font-weight: 400;\">Nessa hora, a tecnologia atua como um grande aux\u00edlio para evitar os desperd\u00edcios. A <\/span><a href=\"http:\/\/www.easyassist.com.br\/?utm_source=blog&amp;utm_medium=post&amp;utm_campaign=blog-lp-easyassist\"><span style=\"font-weight: 400;\">automatiza\u00e7\u00e3o do processo de atendimento<\/span><\/a><span style=\"font-weight: 400;\"> permite que o gar\u00e7om realize os pedidos direto da mesa, sem a necessidade de realizar anota\u00e7\u00f5es, decorar c\u00f3digos ou se deslocar.<\/span><\/p>\n\n\n\n<p><span style=\"font-weight: 400;\">Al\u00e9m de ganhar velocidade, esse tipo de tecnologia evita falhas de comunica\u00e7\u00e3o entre a pra\u00e7a e a cozinha, reduzindo erros e desperd\u00edcios.<\/span><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"7_Use_tecnologia_para_reduzir_o_desperdicio_de_alimentos\"><\/span><b>7. Use tecnologia para reduzir o desperd\u00edcio de alimentos<\/b><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p><span style=\"font-weight: 400;\">A tecnologia pode facilitar voc\u00ea colocar as dicas acima em pr\u00e1tica e ainda estabelecer muitos outros controles que v\u00e3o evitar n\u00e3o s\u00f3 o desperd\u00edcio de alimentos, mas v\u00e1rios outros que podem acarretar em preju\u00edzo no fim do m\u00eas.<\/span><\/p>\n\n\n\n<p><span style=\"font-weight: 400;\">Uma forma de utilizar a tecnologia para reduzir o desperd\u00edcio no restaurante \u00e9 realizar o controle de vendas por meio de <\/span><a href=\"https:\/\/www.casamagalhaes.com.br\/blog\/prevencao-de-perdas\/reduzir-o-desperdicio-de-alimentos\/\"><span style=\"font-weight: 400;\">um sistema de automa\u00e7\u00e3o<\/span><\/a><span style=\"font-weight: 400;\">. Dessa forma, ser\u00e1 poss\u00edvel prever os pratos mais pedidos, obter o volume de vendas por cada dia da semana e assim, realizar uma previs\u00e3o e um melhor controle do que ser\u00e1 produzido.<\/span><\/p>\n\n\n\n<p><span style=\"font-weight: 400;\">Uma outra alternativa interessante para reduzir o desperd\u00edcio de alimentos \u00e9 o uso de <\/span><a href=\"http:\/\/www.easyassist.com.br\/?utm_source=blog&amp;utm_medium=post&amp;utm_campaign=blog-lp-easyassist\"><span style=\"font-weight: 400;\">card\u00e1pios digitais<\/span><\/a><span style=\"font-weight: 400;\">. Estas ferramentas permitem que voc\u00ea altere o menu ao longo do dia e de acordo com a disponibilidade dos pratos, sem a necessidade de uma produ\u00e7\u00e3o desnecess\u00e1ria na cozinha, al\u00e9m de evitar a insatisfa\u00e7\u00e3o dos clientes.<\/span><\/p>\n\n\n\n<p><span style=\"font-weight: 400;\">Agora que voc\u00ea j\u00e1 sabe como reduzir o desperd\u00edcio no restaurante, fique atento para corrigir as falhas e aproveite para assinar nossa newsletter preenchendo o formul\u00e1rio abaixo!<\/span><\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Leia tamb\u00e9m:<\/strong> <a rel=\"noreferrer noopener\" aria-label=\"Guia completo para escolher o melhor sistema para restaurante. (abre numa nova aba)\" href=\"https:\/\/www.casamagalhaes.com.br\/blog\/automacao-comercial\/sistema-para-restaurante\/\" target=\"_blank\"><strong>Guia completo para escolher o melhor sistema para restaurante.<\/strong><\/a><\/h4>\n\n\n\n<div id=\"cta-rodape-post-blog-cadastro-newsletter-5225678ea3f96bcfaa68\"><span style=\"color: #000000;\">&nbsp;<\/span><\/div>\n\n\n\n<p><span style=\"color: #000000;\"><script src=\"https:\/\/d335luupugsy2.cloudfront.net\/js\/rdstation-forms\/stable\/rdstation-forms.min.js\" type=\"text\/javascript\"><\/script><\/span><br><script type=\"text\/javascript\">\/\/ <![CDATA[\nnew RDStationForms('cta-rodape-post-blog-cadastro-newsletter-5225678ea3f96bcfaa68-html', 'UA-45095125-1').createForm();\n\/\/ ]]><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Saiba como reduzir o desperd\u00edcio no restaurante e garantir uma melhor gest\u00e3o do seu estabelecimento! Aprenda conosco atrav\u00e9s de 7 dicas b\u00e1sicas.<\/p>\n","protected":false},"author":3,"featured_media":4156,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"episode_type":"","audio_file":"","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","itunes_episode_number":"","itunes_title":"","itunes_season_number":"","itunes_episode_type":"","ngg_post_thumbnail":0,"footnotes":""},"categories":[150,154],"tags":[119],"class_list":["post-3329","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bares-e-restaurantes","category-gestao-de-empresas","tag-prevencao-de-perdas"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Descubra como reduzir o desperd\u00edcio no restaurante<\/title>\n<meta name=\"description\" content=\"Saiba como reduzir o desperd\u00edcio no restaurante e garantir uma melhor gest\u00e3o do seu estabelecimento! Aprenda conosco atrav\u00e9s de 7 dicas b\u00e1sicas.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.casamagalhaes.com.br\/blog\/bares-e-restaurantes\/reduzir-o-desperdicio-no-restaurante\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Descubra como reduzir o desperd\u00edcio no restaurante\" \/>\n<meta property=\"og:description\" content=\"Saiba como reduzir o desperd\u00edcio no restaurante e garantir uma melhor gest\u00e3o do seu estabelecimento! Aprenda conosco atrav\u00e9s de 7 dicas b\u00e1sicas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.casamagalhaes.com.br\/blog\/bares-e-restaurantes\/reduzir-o-desperdicio-no-restaurante\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog da Casa Magalh\u00e3es\" \/>\n<meta property=\"article:published_time\" content=\"2019-04-22T18:30:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-02-27T21:11:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.casamagalhaes.com.br\/blog\/wp-content\/uploads\/2018\/05\/reduzir-o-desperd\u00edcio-no-restaurante.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"845\" \/>\n\t<meta property=\"og:image:height\" content=\"563\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Casa Magalh\u00e3es\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Casa Magalh\u00e3es\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.casamagalhaes.com.br\\\/blog\\\/bares-e-restaurantes\\\/reduzir-o-desperdicio-no-restaurante\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.casamagalhaes.com.br\\\/blog\\\/bares-e-restaurantes\\\/reduzir-o-desperdicio-no-restaurante\\\/\"},\"author\":{\"name\":\"Casa Magalh\u00e3es\",\"@id\":\"https:\\\/\\\/www.casamagalhaes.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/56c892544a618f4fc2031b11e7b05831\"},\"headline\":\"Como reduzir o desperd\u00edcio no restaurante com essas 7 dicas\",\"datePublished\":\"2019-04-22T18:30:35+00:00\",\"dateModified\":\"2020-02-27T21:11:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.casamagalhaes.com.br\\\/blog\\\/bares-e-restaurantes\\\/reduzir-o-desperdicio-no-restaurante\\\/\"},\"wordCount\":1214,\"commentCount\":2,\"image\":{\"@id\":\"https:\\\/\\\/www.casamagalhaes.com.br\\\/blog\\\/bares-e-restaurantes\\\/reduzir-o-desperdicio-no-restaurante\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.casamagalhaes.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/reduzir-o-desperd\u00edcio-no-restaurante.jpg\",\"keywords\":[\"Preven\u00e7\u00e3o de Perdas\"],\"articleSection\":[\"Food Service\",\"Gest\u00e3o de Empresas\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.casamagalhaes.com.br\\\/blog\\\/bares-e-restaurantes\\\/reduzir-o-desperdicio-no-restaurante\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.casamagalhaes.com.br\\\/blog\\\/bares-e-restaurantes\\\/reduzir-o-desperdicio-no-restaurante\\\/\",\"url\":\"https:\\\/\\\/www.casamagalhaes.com.br\\\/blog\\\/bares-e-restaurantes\\\/reduzir-o-desperdicio-no-restaurante\\\/\",\"name\":\"Descubra como reduzir o desperd\u00edcio no restaurante\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.casamagalhaes.com.br\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.casamagalhaes.com.br\\\/blog\\\/bares-e-restaurantes\\\/reduzir-o-desperdicio-no-restaurante\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.casamagalhaes.com.br\\\/blog\\\/bares-e-restaurantes\\\/reduzir-o-desperdicio-no-restaurante\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.casamagalhaes.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/reduzir-o-desperd\u00edcio-no-restaurante.jpg\",\"datePublished\":\"2019-04-22T18:30:35+00:00\",\"dateModified\":\"2020-02-27T21:11:00+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.casamagalhaes.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/56c892544a618f4fc2031b11e7b05831\"},\"description\":\"Saiba como reduzir o desperd\u00edcio no restaurante e garantir uma melhor gest\u00e3o do seu estabelecimento! Aprenda conosco atrav\u00e9s de 7 dicas b\u00e1sicas.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.casamagalhaes.com.br\\\/blog\\\/bares-e-restaurantes\\\/reduzir-o-desperdicio-no-restaurante\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.casamagalhaes.com.br\\\/blog\\\/bares-e-restaurantes\\\/reduzir-o-desperdicio-no-restaurante\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.casamagalhaes.com.br\\\/blog\\\/bares-e-restaurantes\\\/reduzir-o-desperdicio-no-restaurante\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.casamagalhaes.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/reduzir-o-desperd\u00edcio-no-restaurante.jpg\",\"contentUrl\":\"https:\\\/\\\/www.casamagalhaes.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/reduzir-o-desperd\u00edcio-no-restaurante.jpg\",\"width\":845,\"height\":563},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.casamagalhaes.com.br\\\/blog\\\/bares-e-restaurantes\\\/reduzir-o-desperdicio-no-restaurante\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.casamagalhaes.com.br\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Como reduzir o desperd\u00edcio no restaurante com essas 7 dicas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.casamagalhaes.com.br\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.casamagalhaes.com.br\\\/blog\\\/\",\"name\":\"Blog da Casa Magalh\u00e3es\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.casamagalhaes.com.br\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.casamagalhaes.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/56c892544a618f4fc2031b11e7b05831\",\"name\":\"Casa Magalh\u00e3es\",\"description\":\"Somos um Grupo empresarial da ind\u00fastria de TI, refer\u00eancia no mercado nacional de automa\u00e7\u00e3o comercial desde 1966, composto por empresas que desenvolvem softwares integrados de gest\u00e3o empresarial e frente de loja. Possui atendimento comercial, implanta\u00e7\u00e3o e suporte em todas as capitais do Brasil atrav\u00e9s de uma ampla rede de parceiros credenciados.\",\"sameAs\":[\"http:\\\/\\\/www.casamagalhaes.com.br\",\"https:\\\/\\\/www.instagram.com\\\/grupocasamagalhaes\\\/?hl=pt-br\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Descubra como reduzir o desperd\u00edcio no restaurante","description":"Saiba como reduzir o desperd\u00edcio no restaurante e garantir uma melhor gest\u00e3o do seu estabelecimento! Aprenda conosco atrav\u00e9s de 7 dicas b\u00e1sicas.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.casamagalhaes.com.br\/blog\/bares-e-restaurantes\/reduzir-o-desperdicio-no-restaurante\/","og_locale":"pt_BR","og_type":"article","og_title":"Descubra como reduzir o desperd\u00edcio no restaurante","og_description":"Saiba como reduzir o desperd\u00edcio no restaurante e garantir uma melhor gest\u00e3o do seu estabelecimento! Aprenda conosco atrav\u00e9s de 7 dicas b\u00e1sicas.","og_url":"https:\/\/www.casamagalhaes.com.br\/blog\/bares-e-restaurantes\/reduzir-o-desperdicio-no-restaurante\/","og_site_name":"Blog da Casa Magalh\u00e3es","article_published_time":"2019-04-22T18:30:35+00:00","article_modified_time":"2020-02-27T21:11:00+00:00","og_image":[{"width":845,"height":563,"url":"https:\/\/www.casamagalhaes.com.br\/blog\/wp-content\/uploads\/2018\/05\/reduzir-o-desperd\u00edcio-no-restaurante.jpg","type":"image\/jpeg"}],"author":"Casa Magalh\u00e3es","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Casa Magalh\u00e3es","Est. tempo de leitura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.casamagalhaes.com.br\/blog\/bares-e-restaurantes\/reduzir-o-desperdicio-no-restaurante\/#article","isPartOf":{"@id":"https:\/\/www.casamagalhaes.com.br\/blog\/bares-e-restaurantes\/reduzir-o-desperdicio-no-restaurante\/"},"author":{"name":"Casa Magalh\u00e3es","@id":"https:\/\/www.casamagalhaes.com.br\/blog\/#\/schema\/person\/56c892544a618f4fc2031b11e7b05831"},"headline":"Como reduzir o desperd\u00edcio no restaurante com essas 7 dicas","datePublished":"2019-04-22T18:30:35+00:00","dateModified":"2020-02-27T21:11:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.casamagalhaes.com.br\/blog\/bares-e-restaurantes\/reduzir-o-desperdicio-no-restaurante\/"},"wordCount":1214,"commentCount":2,"image":{"@id":"https:\/\/www.casamagalhaes.com.br\/blog\/bares-e-restaurantes\/reduzir-o-desperdicio-no-restaurante\/#primaryimage"},"thumbnailUrl":"https:\/\/www.casamagalhaes.com.br\/blog\/wp-content\/uploads\/2018\/05\/reduzir-o-desperd\u00edcio-no-restaurante.jpg","keywords":["Preven\u00e7\u00e3o de Perdas"],"articleSection":["Food Service","Gest\u00e3o de Empresas"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.casamagalhaes.com.br\/blog\/bares-e-restaurantes\/reduzir-o-desperdicio-no-restaurante\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.casamagalhaes.com.br\/blog\/bares-e-restaurantes\/reduzir-o-desperdicio-no-restaurante\/","url":"https:\/\/www.casamagalhaes.com.br\/blog\/bares-e-restaurantes\/reduzir-o-desperdicio-no-restaurante\/","name":"Descubra como reduzir o desperd\u00edcio no restaurante","isPartOf":{"@id":"https:\/\/www.casamagalhaes.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.casamagalhaes.com.br\/blog\/bares-e-restaurantes\/reduzir-o-desperdicio-no-restaurante\/#primaryimage"},"image":{"@id":"https:\/\/www.casamagalhaes.com.br\/blog\/bares-e-restaurantes\/reduzir-o-desperdicio-no-restaurante\/#primaryimage"},"thumbnailUrl":"https:\/\/www.casamagalhaes.com.br\/blog\/wp-content\/uploads\/2018\/05\/reduzir-o-desperd\u00edcio-no-restaurante.jpg","datePublished":"2019-04-22T18:30:35+00:00","dateModified":"2020-02-27T21:11:00+00:00","author":{"@id":"https:\/\/www.casamagalhaes.com.br\/blog\/#\/schema\/person\/56c892544a618f4fc2031b11e7b05831"},"description":"Saiba como reduzir o desperd\u00edcio no restaurante e garantir uma melhor gest\u00e3o do seu estabelecimento! Aprenda conosco atrav\u00e9s de 7 dicas b\u00e1sicas.","breadcrumb":{"@id":"https:\/\/www.casamagalhaes.com.br\/blog\/bares-e-restaurantes\/reduzir-o-desperdicio-no-restaurante\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.casamagalhaes.com.br\/blog\/bares-e-restaurantes\/reduzir-o-desperdicio-no-restaurante\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.casamagalhaes.com.br\/blog\/bares-e-restaurantes\/reduzir-o-desperdicio-no-restaurante\/#primaryimage","url":"https:\/\/www.casamagalhaes.com.br\/blog\/wp-content\/uploads\/2018\/05\/reduzir-o-desperd\u00edcio-no-restaurante.jpg","contentUrl":"https:\/\/www.casamagalhaes.com.br\/blog\/wp-content\/uploads\/2018\/05\/reduzir-o-desperd\u00edcio-no-restaurante.jpg","width":845,"height":563},{"@type":"BreadcrumbList","@id":"https:\/\/www.casamagalhaes.com.br\/blog\/bares-e-restaurantes\/reduzir-o-desperdicio-no-restaurante\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.casamagalhaes.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Como reduzir o desperd\u00edcio no restaurante com essas 7 dicas"}]},{"@type":"WebSite","@id":"https:\/\/www.casamagalhaes.com.br\/blog\/#website","url":"https:\/\/www.casamagalhaes.com.br\/blog\/","name":"Blog da Casa Magalh\u00e3es","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.casamagalhaes.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/www.casamagalhaes.com.br\/blog\/#\/schema\/person\/56c892544a618f4fc2031b11e7b05831","name":"Casa Magalh\u00e3es","description":"Somos um Grupo empresarial da ind\u00fastria de TI, refer\u00eancia no mercado nacional de automa\u00e7\u00e3o comercial desde 1966, composto por empresas que desenvolvem softwares integrados de gest\u00e3o empresarial e frente de loja. Possui atendimento comercial, implanta\u00e7\u00e3o e suporte em todas as capitais do Brasil atrav\u00e9s de uma ampla rede de parceiros credenciados.","sameAs":["http:\/\/www.casamagalhaes.com.br","https:\/\/www.instagram.com\/grupocasamagalhaes\/?hl=pt-br"]}]}},"_links":{"self":[{"href":"https:\/\/www.casamagalhaes.com.br\/blog\/wp-json\/wp\/v2\/posts\/3329","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.casamagalhaes.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.casamagalhaes.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.casamagalhaes.com.br\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.casamagalhaes.com.br\/blog\/wp-json\/wp\/v2\/comments?post=3329"}],"version-history":[{"count":15,"href":"https:\/\/www.casamagalhaes.com.br\/blog\/wp-json\/wp\/v2\/posts\/3329\/revisions"}],"predecessor-version":[{"id":6993,"href":"https:\/\/www.casamagalhaes.com.br\/blog\/wp-json\/wp\/v2\/posts\/3329\/revisions\/6993"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.casamagalhaes.com.br\/blog\/wp-json\/wp\/v2\/media\/4156"}],"wp:attachment":[{"href":"https:\/\/www.casamagalhaes.com.br\/blog\/wp-json\/wp\/v2\/media?parent=3329"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.casamagalhaes.com.br\/blog\/wp-json\/wp\/v2\/categories?post=3329"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.casamagalhaes.com.br\/blog\/wp-json\/wp\/v2\/tags?post=3329"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}